{"id":830,"date":"2015-07-18T15:42:45","date_gmt":"2015-07-18T14:42:45","guid":{"rendered":"http:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg"},"modified":"2015-07-18T16:24:46","modified_gmt":"2015-07-18T15:24:46","slug":"0123_nella_barigazzi","status":"inherit","type":"attachment","link":"https:\/\/www.ilfederson.eu\/wordpress\/0123_nella_barigazzi","title":{"rendered":"Nella Barigazzi articolo di giornale"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-830","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nella Barigazzi articolo di giornale - I. L. Federson<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nella Barigazzi articolo di giornale - I. L. Federson\" \/>\n<meta property=\"og:description\" content=\"Nella Barigazzi in un giornale degli anni &#039;40\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\" \/>\n<meta property=\"og:site_name\" content=\"I. L. Federson\" \/>\n<meta property=\"article:modified_time\" content=\"2015-07-18T15:24:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"334\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\",\"url\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\",\"name\":\"Nella Barigazzi articolo di giornale - I. L. Federson\",\"isPartOf\":{\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#website\"},\"datePublished\":\"2015-07-18T14:42:45+00:00\",\"dateModified\":\"2015-07-18T15:24:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ilfederson.eu\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nella Barigazzi articolo di giornale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#website\",\"url\":\"https:\/\/www.ilfederson.eu\/wordpress\/\",\"name\":\"I. L. Federson\",\"description\":\"Autore dei racconti del maresciallo Ferretti\",\"publisher\":{\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/3f0e44ebe87a3e66a829363066155026\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ilfederson.eu\/wordpress\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/3f0e44ebe87a3e66a829363066155026\",\"name\":\"I L Federson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\",\"contentUrl\":\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg\",\"width\":334,\"height\":515,\"caption\":\"I L Federson\"},\"logo\":{\"@id\":\"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/www.ilfederson.eu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nella Barigazzi articolo di giornale - I. L. Federson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","og_locale":"en_US","og_type":"article","og_title":"Nella Barigazzi articolo di giornale - I. L. Federson","og_description":"Nella Barigazzi in un giornale degli anni '40","og_url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","og_site_name":"I. L. Federson","article_modified_time":"2015-07-18T15:24:46+00:00","og_image":[{"width":334,"height":515,"url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","name":"Nella Barigazzi articolo di giornale - I. L. Federson","isPartOf":{"@id":"https:\/\/www.ilfederson.eu\/wordpress\/#website"},"datePublished":"2015-07-18T14:42:45+00:00","dateModified":"2015-07-18T15:24:46+00:00","breadcrumb":{"@id":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ilfederson.eu\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Nella Barigazzi articolo di giornale"}]},{"@type":"WebSite","@id":"https:\/\/www.ilfederson.eu\/wordpress\/#website","url":"https:\/\/www.ilfederson.eu\/wordpress\/","name":"I. L. Federson","description":"Autore dei racconti del maresciallo Ferretti","publisher":{"@id":"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/3f0e44ebe87a3e66a829363066155026"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ilfederson.eu\/wordpress\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/3f0e44ebe87a3e66a829363066155026","name":"I L Federson","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/image\/","url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","contentUrl":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","width":334,"height":515,"caption":"I L Federson"},"logo":{"@id":"https:\/\/www.ilfederson.eu\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.ilfederson.eu"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"195\" height=\"300\" src=\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi-195x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Nella Barigazzi articolo di giornale\" srcset=\"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi-195x300.jpg 195w, https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg 334w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/a><\/p>\n<p>Nella Barigazzi ultimo testimone del caso di Leonarda Cianciulli &#8211; la &#8220;saponificatrice di Correggio&#8221;<\/p>\n"},"caption":{"rendered":"<p>Nella Barigazzi in un giornale degli anni &#8217;40<\/p>\n"},"alt_text":"Nella Barigazzi articolo di giornale","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":334,"height":515,"file":"2015\/07\/0123_Nella_Barigazzi.jpg","sizes":{"thumbnail":{"file":"0123_Nella_Barigazzi-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi-150x150.jpg"},"medium":{"file":"0123_Nella_Barigazzi-195x300.jpg","width":195,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi-195x300.jpg"},"full":{"file":"0123_Nella_Barigazzi.jpg","width":334,"height":515,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/www.ilfederson.eu\/wordpress\/wp-content\/uploads\/2015\/07\/0123_Nella_Barigazzi.jpg","filename":"0123_Nella_Barigazzi.jpg","filesize":75371,"_links":{"self":[{"href":"https:\/\/www.ilfederson.eu\/wordpress\/wp-json\/wp\/v2\/media\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilfederson.eu\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ilfederson.eu\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilfederson.eu\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilfederson.eu\/wordpress\/wp-json\/wp\/v2\/comments?post=830"}]}}